{"slug":"convenio-psicologos","excerpt":{"rendered":"<p>Em busca de melhorias para a categoria de Psic\u00f3logas(os) do Estado do Tocantins, o CRP 23 sob a gest\u00e3o do Conselheiro Presidente Arivandre Tavares, traz conv\u00eanios\/parcerias para as(os) psic\u00f3logas(os) que estejam devidamente inscritos, regulares e adimplentes com o CRP23. Para&#8230; <a class=\"moretag\" href=\"https:\/\/transparencia.cfp.org.br\/crp23\/psicologo\/convenio-psicologos\/\">Continue lendo<\/a><\/p>\n","protected":false},"titulo":"Conv\u00eanio Psic\u00f3logos","conteudo":"Em busca de melhorias para a categoria de Psic\u00f3logas(os) do Estado do Tocantins, o CRP 23 sob a gest\u00e3o do Conselheiro Presidente Arivandre Tavares, traz conv\u00eanios\/parcerias para as(os) psic\u00f3logas(os) que estejam devidamente inscritos, regulares e adimplentes com o CRP23.\nPara aproveitar o desconto, basta apresentar a Carteira de Identidade Profissional de Psicologia. Esta oferta \u00e9 v\u00e1lida para todos as (os) psic\u00f3logas (os).\nA seguir os conv\u00eanios\/parcerias que j\u00e1 est\u00e3o em funcionamento com os seus seguintes descontos:\n\n\u00a0Academia RG Fitness,\u00a0\u00a0desconto de 20%\u00a0nas mensalidades. Para mais detalhes, acesse o\u00a0link.\nAdriana Bombons da 104 Norte,\u00a0desconto de 10%\u00a0nos produtos em geral.\u00a0Para mais detalhes, acesse o\u00a0link.\nAsmir (hotel de tr\u00e2nsito),\u00a0\u00a0desconto com di\u00e1rias a partir de 95 reais com caf\u00e9 da manh\u00e3.\u00a0Para mais detalhes, acesse o\u00a0link.\nCDL Certifica\u00e7\u00e3o Digital,\u00a0oferece\u00a0descontos especiais.\u00a0Para mais detalhes, acesse o\u00a0link.\nCNA Instituto de Idiomas,\u00a0desconto de 30%\u00a0em todas as mensalidades.\u00a0Para mais detalhes, acesse o\u00a0link.\nCreche Pequeno Pr\u00edncipe,\u00a0\u00a0desconto de 15%\u00a0na matr\u00edcula e nas mensalidades.\u00a0Para mais detalhes, acesse o\u00a0link.\nIPE Odontologia,\u00a0desconto de 10%\u00a0em todas as presta\u00e7\u00f5es continuadas de servi\u00e7os de Assist\u00eancia Odontol\u00f3gica.\u00a0Para mais detalhes, acesse o\u00a0link.\nIPOG \u2013 Instituto de P\u00f3s-gradua\u00e7\u00e3o e Gradua\u00e7\u00e3o,\u00a0\u00a0oferece um incr\u00edvel\u00a0desconto.\u00a0Para mais detalhes, acesse o\u00a0link.\nNutri+ Suplementos,\u00a0desconto de 5%\u00a0nas compras na loja ou no site.\u00a0Para mais detalhes, acesse o\u00a0link.\nPapelaria Moderna,\u00a0\u00a0desconto de 20%\u00a0nas compras em geral.\u00a0Para mais detalhes, acesse o\u00a0link.\nSM Excel\u00eancia em Odontologia,\u00a0desconto de 20%\u00a0nos atendimentos e procedimentos em geral.\u00a0Para mais detalhes, acesse o\u00a0link.\nUnimed, oferecendo planos de sa\u00fade para todas(os) as(os) profissionais de Psicologia. Para mais detalhes, acesse o\u00a0link.\n\n\n\n\n"}