{"slug":"tabelas-de-remuneracao","excerpt":{"rendered":"<p>Informa\u00e7\u00f5es sobre as Tabelas de Remunera\u00e7\u00e3o do Conselho Regional de Psicologia &#8211; 23\u00aa Regi\u00e3o. &nbsp; A tabela de remunera\u00e7\u00e3o do CRP 23, foi definida pelas resolu\u00e7\u00f5es: CRP 23 n\u00ba 24\/2024, atualizada pela Resolu\u00e7\u00e3o CRP 23 n\u00ba 29\/2024. Resolu\u00e7\u00f5e CRP 23&#8230; <a class=\"moretag\" href=\"https:\/\/transparencia.cfp.org.br\/crp23\/gestao-de-pessoas\/tabelas-de-remuneracao\/\">Continue lendo<\/a><\/p>\n","protected":false},"titulo":"Tabelas de Remunera\u00e7\u00e3o","conteudo":"Informa\u00e7\u00f5es sobre as Tabelas de Remunera\u00e7\u00e3o do Conselho Regional de Psicologia \u2013 23\u00aa Regi\u00e3o.\n\u00a0\nA tabela de remunera\u00e7\u00e3o do CRP 23, foi definida pelas resolu\u00e7\u00f5es: CRP 23 n\u00ba 24\/2024, atualizada pela Resolu\u00e7\u00e3o CRP 23 n\u00ba 29\/2024. Resolu\u00e7\u00f5e CRP 23 n\u00ba 33\/2026, n\u00ba 34\/2026 e n\u00ba 35\/2026. Vejamos a tabela atual do CRP 23:\nTABELA DE REMUNERA\u00c7\u00d5ES 2026.\n\u00a0\nTabela do CRP 23 em transi\u00e7\u00e3o\/extin\u00e7\u00e3o:\nA tabela de remunera\u00e7\u00e3o do CRP 23, foi definida pela Resolu\u00e7\u00e3o CRP 23 n\u00ba 24\/2024, atualizada pela Resolu\u00e7\u00e3o CRP 23 n\u00ba 29\/2024.\nTabela de Remunera\u00e7\u00e3o do ano de 2024.\n\u00a0\nQuadro-de-Pessoal-do-CRP-23-2022\n"}