{"id":805,"slug":"ementa-institui-o-codigo-de-processamento-disciplinar-resolucao-n-0062007","link":"https:\/\/transparencia.cfp.org.br\/crp23\/legislacao\/ementa-institui-o-codigo-de-processamento-disciplinar-resolucao-n-0062007\/","class_list":["post-805","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-codigo-de-processo-disciplinar"],"titulo":"Resolu\u00e7\u00e3o N\u00b0 006\/2007 \u2013 C\u00f3digo de Processamento Disciplinar","conteudo":"Foi atualizado pelo C\u00f3digo de Processamento Disciplinar de 2019.\n","documentos":[{"file_uploaded":1842,"document_name":"C\u00f3digo de Processamento Disciplinar - Resolu\u00e7\u00e3o N\u00b0 006\/2007","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2007\/03\/Resolu\u00e7\u00e3o-006-2007-Institui-o-C\u00f3digo-de-Processamento-Disciplinar.pdf"}],"_legislacao_categoria":[{"id":11,"nome":"C\u00f3digo de processo disciplinar","slug":"codigo-de-processo-disciplinar","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=codigo-de-processo-disciplinar"}]}