{"id":2209,"slug":"balancete-2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/financa\/balancete-2018\/","class_list":["post-2209","financa","type-financa","status-publish","hentry","financa_demonstrativo-balancete"],"documentos":[{"file_uploaded":2210,"document_name":"Balancete Janeiro - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/BALANCETE-JANEIRO-2018.pdf"},{"file_uploaded":2211,"document_name":"Balancete Fevereiro - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/BALANCETE-FEVEREIRO-2018.pdf"},{"file_uploaded":2268,"document_name":"Balancete Mar\u00e7o - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/BALANCETE-MAR\u00c7O-2018.pdf"},{"file_uploaded":2309,"document_name":"Balancete Abril - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/BALANCETE-ABRIL-2018.pdf"},{"file_uploaded":2352,"document_name":"Balancete Maio - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/BALANCETE-05-2018.pdf"},{"file_uploaded":2762,"document_name":"Balancete Dezembro - 2018","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2018\/04\/10-Balancete.pdf"}],"_financa_demonstrativo":[{"id":53,"nome":"Balancete","slug":"balancete","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=balancete"}],"titulo":"Balancete do ano de 2018","conteudo":""}