{"id":1598,"slug":"comparativo-da-receita-2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/financa\/comparativo-da-receita-2017\/","class_list":["post-1598","financa","type-financa","status-publish","hentry","financa_demonstrativo-comparativo-da-receita"],"documentos":[{"file_uploaded":1599,"document_name":" Comparativo da Receita - Janeiro 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-Janeiro-2017.pdf"},{"file_uploaded":1600,"document_name":"Comparativo de Receita - Fevereiro 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-de-Receita-Fevereiro-2017.pdf"},{"file_uploaded":1601,"document_name":" Comparativo da Receita - Mar\u00e7o 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-Mar\u00e7o-2017.pdf"},{"file_uploaded":1964,"document_name":" Comparativo da Receita - Abril 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-04-2017.pdf"},{"file_uploaded":1965,"document_name":" Comparativo da Receita - Maio 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-05-2017.pdf"},{"file_uploaded":1966,"document_name":" Comparativo da Receita - Junho 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-06-2017.pdf"},{"file_uploaded":1967,"document_name":" Comparativo da Receita - Julho 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-07-2017.pdf"},{"file_uploaded":1976,"document_name":" Comparativo da Receita - Agosto 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-08-2017.pdf"},{"file_uploaded":1987,"document_name":" Comparativo da Receita - Setembro 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-09-2017.pdf"},{"file_uploaded":2044,"document_name":"Comparativo da Receita - Outubro 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/Comparativo-da-Receita-10-2017.pdf"},{"file_uploaded":2126,"document_name":"Comparativo da Receita -  Anual 2017","link":"https:\/\/transparencia.cfp.org.br\/crp23\/wp-content\/uploads\/sites\/10\/2017\/05\/COMPARATIVO-DA-RECEITA-2017.pdf"}],"_financa_demonstrativo":[{"id":45,"nome":"Comparativo da Receita","slug":"comparativo-da-receita","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=comparativo-da-receita"}],"titulo":"Comparativo de Receita do ano de 2017","conteudo":""}