{"id":4938,"slug":"processo-eleitoral-2025","link":"https:\/\/transparencia.cfp.org.br\/crp20\/eleicao\/processo-eleitoral-2025\/","class_list":["post-4938","eleicao","type-eleicao","status-publish","hentry"],"documentos":[{"file_uploaded":4940,"document_name":"REGIMENTO ELEITORAL","link":"https:\/\/transparencia.cfp.org.br\/crp20\/wp-content\/uploads\/sites\/16\/2025\/07\/Regimento-Eleitoral.pdf"},{"file_uploaded":4941,"document_name":"EDITAL DE CONVOCA\u00c7\u00c3O PARA AS ELEI\u00c7\u00d5ES DE 2025","link":"https:\/\/transparencia.cfp.org.br\/crp20\/wp-content\/uploads\/sites\/16\/2025\/07\/EDITAL-DE-CONVOCACAO-PARA-AS-ELEICOES-2025-CRP-20-INSCRICAO-DE-CHAPAS.pdf"},{"file_uploaded":5006,"document_name":"EDITAL ATUALIZADO DE CONVOCA\u00c7\u00c3O COMPLETO CHAPAS HOMOLOGADAS_ ELEI\u00c7\u00d5ES DE 2025","link":"https:\/\/transparencia.cfp.org.br\/crp20\/wp-content\/uploads\/sites\/16\/2025\/07\/Edital_atualizado_de_Convocacao_para_as_Eleicoes_2025_completo_.pdf"},{"file_uploaded":5039,"document_name":"TREMO DE POSSE VI PLEN\u00c1RIO 2025_2028","link":"https:\/\/transparencia.cfp.org.br\/crp20\/wp-content\/uploads\/sites\/16\/2025\/07\/TERMO-DE-POSSE-VI-PLENARIO-2025_2028-1.pdf"}],"titulo":"PROCESSO ELEITORAL 2025","conteudo":"As elei\u00e7\u00f5es no Sistema Conselhos de Psicologia acontecem de 3 em 3 anos, pelo sistema de chapas \u2013 que s\u00e3o inscritas nos COREPs, quando regionais, e no CNP, quando nacionais. No ano de 2025, os pleitos ser\u00e3o realizados entre os dias 23 a 27 de agosto.\nAs chapas inscritas que concorrem \u00e0s elei\u00e7\u00f5es do Conselho Regional de Psicologia da 20 Regi\u00e3o AM\/ RR s\u00e3o:\n\n\n\nCHAPA n\u00ba 11 FRENTE EM DEFESA DA PSICOLOGIA: CI\u00caNCIA E PROFISS\u00c3O\n\n\nNome Completo\nComo prefere ser chamada\nCRP\n\n\nCarlos Roberto dos Prazeres Santos\nCarlos Santos\nCRP20 \u2013 RR 02631\n\n\nCris\u00e2ngela Nascimento de Menezes\nCris\u00e2ngela Menezes\nCRP20 \u2013 AM 04941\n\n\nDaniel Ribeiro Arteiro\nDaniel Arteiro\nCRP20 \u2013 AM 11827\n\n\n\u2060Davi Gonz\u00e1lez Ramos\n\u2060Davi Gonz\u00e1lez\nCRP20 \u2013 AM 12074\n\n\nElaine Cristina Brito Machado\nElaine Brito\nCRP20 \u2013 RR 03888\n\n\n\u2060Gibson Alves dos Santos\n\u2060Gibson Santos\nCRP20 \u2013 AM 00174\n\n\nIracilda Neves Lima\nIracilda Neves\nCRP20 \u2013 AM 01397\n\n\nJose Humberto da Silva Filho\nJose Humberto\nCRP20 \u2013 AM 03750\n\n\nLuciana Gomes do Nascimento\nLuciana Gomes\nCRP20 \u2013 AM 09202\n\n\nMagaly Silva de Oliveira\nMagaly Oliveira\nCRP20 \u2013 AM 01582\n\n\nMichella Mendon\u00e7a Aguiar de Oliveira\nMichella Aguiar\nCRP20 \u2013 AM 04503\n\n\nMonica Crystina Lopes Maximino\nMonica Maximino\nCRP20 \u2013 AM 07096\n\n\nN\u00fabia Santos dos Reis\nN\u00fabia Reis\nCRP20 \u2013 AM 05909\n\n\nPerina de F\u00e1tima Aguiar Costa\nPerina Costa\nCRP20 \u2013 AM 03475\n\n\nSidney dos Santos Filho\nSidney Filho\nCRP20 \u2013 AM 08236\n\n\nSilvia Silvestre Barreto\nSilvia Barreto\nCRP20 \u2013 AM 08784\n\n\nSulamita Pinto Neves\nSulamita Neves\nCRP20 \u2013 AM 11565\n\n\n\u2060Wendell Scott Braga de Almeida\n\u2060Wendell Scott\nCRP20 \u2013 AM 10753\n\n\n\n\n\n\nChapa n\u00ba 12 Amaz\u00f4nida: para Esperan\u00e7ar, Resistir e Politizar a Psicologia no Amazonas e em Roraima\n\n\nNome Completo\nComo prefere ser chamada\nCRP\n\n\nAdria de Lima Sousa\nAdria Lima\nCRP20 \u2013 AM 04636\n\n\nAlcenir Pereira Gomes\nEny Gomes\nCRP20 \u2013 AM 09087\n\n\nAndr\u00e9 Luiz Machado das Neves\nAndr\u00e9 Machado\nCRP20 \u2013 AM 07009\n\n\nB\u00e1rbara Prata Gordiano\nB\u00e1rbara Prata\nCRP20 \u2013 AM 09641\n\n\nCaio Jos\u00e9 Lucius Braz\u00e3o de Lima\nCaio Braz\u00e3o\nCRP20 \u2013 RR 10849\n\n\nCan\u00ed Jakson Alves da Silva\nCan\u00ed Silva\nCRP20 \u2013 AM 11054\n\n\nElayne Cristina dos Santos Cardoso\nElayne Cardoso\nCRP20 \u2013 AM 07904\n\n\nEster Nai\u00e1 Ferreira Melo\nEster Nai\u00e1\nCRP20 \u2013 AM 12065\n\n\nGizelly de Carvalho Martins\nGizelly Martins\nCRP20 \u2013 AM 01340\n\n\nHelenilson dos Santos Mota\nHelenilson Mota (Heleno)\nCRP20 \u2013 AM 10441\n\n\nIterniza Pereira Andr\u00e9\nIterniza Macuxi\nCRP20 \u2013 RR 09967\n\n\nJana\u00edna L\u00e9ia Passos da Silva\nJana\u00edna Leia Amaz\u00f4nida do Rio Madeira\nCRP20 \u2013 AM 11781\n\n\nJo\u00e3o Lucas da Silva Ramos\nJo\u00e3o Lucas Ramos\nCRP20 \u2013 AM 09180\n\n\nJolorena de Paula Tavares\nJolorena de Paula (Jlo)\nCRP20 \u2013 AM 11719\n\n\nMagali Monteiro da Silva\nMagali Monteiro\nCRP20 \u2013 AM 08411\n\n\nMirlane Karen Mendes Nunes\nMirlane Nunes\nCRP20 \u2013 RR 06806\n\n\nRodrigo Serr\u00e3o de Farias\nRodrigo Serr\u00e3o\nCRP20 \u2013 AM 08117\n\n\nTain\u00e1 Conde Pinto\nTain\u00e1 Conde\nCRP20 \u2013 AM 09229\n\n\n\n\u00a0\n\u00a0\n"}