{"id":5774,"slug":"balanco-orcamentario_agosto2021","link":"https:\/\/transparencia.cfp.org.br\/crp19\/financa\/balanco-orcamentario_agosto2021\/","class_list":["post-5774","financa","type-financa","status-publish","hentry","financa_demonstrativo-balanco-orcamentario"],"documentos":[{"file_uploaded":5775,"document_name":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2021","link":"https:\/\/transparencia.cfp.org.br\/crp19\/wp-content\/uploads\/sites\/11\/2021\/12\/Balanco-Orcamentario-Agosto.pdf"}],"_financa_demonstrativo":[{"id":6,"nome":"Balan\u00e7o Or\u00e7ament\u00e1rio","slug":"balanco-orcamentario","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=balanco-orcamentario"}],"titulo":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2021","conteudo":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2021\n"}