{"id":5021,"slug":"balanco-orcamentario-agosto2020","link":"https:\/\/transparencia.cfp.org.br\/crp19\/financa\/balanco-orcamentario-agosto2020\/","class_list":["post-5021","financa","type-financa","status-publish","hentry","financa_demonstrativo-balanco-orcamentario"],"documentos":[{"file_uploaded":5023,"document_name":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2020","link":"https:\/\/transparencia.cfp.org.br\/crp19\/wp-content\/uploads\/sites\/11\/2020\/11\/Balanco-Orcamentario-Agosto2020.pdf"}],"_financa_demonstrativo":[{"id":6,"nome":"Balan\u00e7o Or\u00e7ament\u00e1rio","slug":"balanco-orcamentario","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=balanco-orcamentario"}],"titulo":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2020","conteudo":"Balan\u00e7o Or\u00e7ament\u00e1rio_Agosto2020\n"}