{"id":3537,"slug":"resolucao-n-003-2019","link":"https:\/\/transparencia.cfp.org.br\/crp14\/legislacao\/resolucao-n-003-2019\/","class_list":["post-3537","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-resolucoes-do-crp"],"titulo":"Resolu\u00e7\u00e3o CRP14 N.003\/2019","conteudo":"Disp\u00f5e sobre o reembolso do pagamento do conv\u00eanio de Assist\u00eancia M\u00e9dica aos servidores do Conselho Regional de Psicologia 14\u00aa Regi\u00e3o MS.\n","documentos":[{"file_uploaded":3538,"document_name":"Resolu\u00e7\u00e3o CRP14 N.003\/2019","link":"https:\/\/transparencia.cfp.org.br\/crp14\/wp-content\/uploads\/sites\/7\/2019\/08\/Res-CRP14MS.003.2019-Plano-de-Sa\u00fade.pdf"}],"_legislacao_categoria":[{"id":44,"nome":"Resolu\u00e7\u00f5es do CRP14MS","slug":"resolucoes-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=resolucoes-do-crp"}]}