
{"id":7771,"slug":"ata-de-recomposicao-da-mesa-diretora-21-08-2026","link":"https:\/\/transparencia.cfp.org.br\/crp14\/ata\/ata-de-recomposicao-da-mesa-diretora-21-08-2026\/","class_list":["post-7771","ata","type-ata","status-publish","hentry","ata_reuniao-eleicao-e-posse-de-diretoria"],"documentos":[{"file_uploaded":7772,"document_name":"Ata de Recomposi\u00e7\u00e3o da Mesa Diretora","link":"https:\/\/transparencia.cfp.org.br\/crp14\/wp-content\/uploads\/sites\/7\/2026\/08\/SEI_3033752_Ata_de_Reuniao_Plenaria_434_.pdf"},{"file_uploaded":7776,"document_name":"Lista de presen\u00e7a","link":"https:\/\/transparencia.cfp.org.br\/crp14\/wp-content\/uploads\/sites\/7\/2026\/08\/lista.pdf"}],"_ata_reuniao":[{"id":53,"nome":"Elei\u00e7\u00e3o e Posse De Diretoria","slug":"eleicao-e-posse-de-diretoria","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/ata?atareuniao=eleicao-e-posse-de-diretoria"}],"titulo":"Ata de Recomposi\u00e7\u00e3o da Mesa Diretora \u2013 21\/08\/2026","conteudo":"Ata de Recomposi\u00e7\u00e3o da Mesa Diretora\n"}