{"id":4312,"slug":"ata-sessao-plenaria-ordinaria-18-09-2020","link":"https:\/\/transparencia.cfp.org.br\/crp14\/ata\/ata-sessao-plenaria-ordinaria-18-09-2020\/","class_list":["post-4312","ata","type-ata","status-publish","hentry","ata_reuniao-plenaria"],"documentos":[{"file_uploaded":4353,"document_name":"Ata 344\u00aa","link":"https:\/\/transparencia.cfp.org.br\/crp14\/wp-content\/uploads\/sites\/7\/2020\/09\/ATA-344-18.09.2020.pdf"}],"_ata_reuniao":[{"id":27,"nome":"Plen\u00e1ria","slug":"plenaria","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/ata?atareuniao=plenaria"}],"titulo":"Ata Sess\u00e3o Plen\u00e1ria Ordin\u00e1ria 18\/09\/2020","conteudo":"Ata Sess\u00e3o Plen\u00e1ria Ordin\u00e1ria 18\/09\/2020\n"}