{"id":3497,"slug":"ata-sessao-plenaria-ordinaria-15-04-2019","link":"https:\/\/transparencia.cfp.org.br\/crp14\/ata\/ata-sessao-plenaria-ordinaria-15-04-2019\/","class_list":["post-3497","ata","type-ata","status-publish","hentry","ata_reuniao-plenaria"],"documentos":[{"file_uploaded":3578,"document_name":"Ata Sess\u00e3o Plen\u00e1ria Ordin\u00e1ria 15\/04\/2019","link":"https:\/\/transparencia.cfp.org.br\/crp14\/wp-content\/uploads\/sites\/7\/2019\/04\/ATA-323-15.04.2019.pdf"}],"_ata_reuniao":[{"id":27,"nome":"Plen\u00e1ria","slug":"plenaria","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/ata?atareuniao=plenaria"}],"titulo":"Ata Sess\u00e3o Plen\u00e1ria Ordin\u00e1ria 15\/04\/2019","conteudo":"Ata Sess\u00e3o Plen\u00e1ria Ordin\u00e1ria 15\/04\/2019\n"}