{"id":1641,"slug":"concurso-2012","link":"https:\/\/transparencia.cfp.org.br\/crp09\/concurso\/concurso-2012\/","class_list":["post-1641","concurso","type-concurso","status-publish","hentry"],"titulo":"Concurso 2012","conteudo":"","documentos":[{"file_uploaded":1642,"document_name":"Edital","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/EDITAL-CONCURSO-2012.pdf"},{"file_uploaded":1643,"document_name":"Homologa\u00e7\u00e3o","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/Homologacao.pdf"},{"file_uploaded":1644,"document_name":"Resultado Final Analista Administrativo Goi\u00e2nia","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ANALISTA-ADMINISTRATIVO-I-GOI\u00c2NIA.pdf"},{"file_uploaded":1645,"document_name":"Resultado Final Analista de Fiscaliza\u00e7\u00e3o Goi\u00e2nia","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ANALISTA-DE-FISCALIZA\u00c7\u00c3O-I-GOI\u00c2NIA.pdf"},{"file_uploaded":1646,"document_name":"Resultado Final Analista de Fiscaliza\u00e7\u00e3o Palmas","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ANALISTA-DE-FISCALIZA\u00c7\u00c3O-I-PALMAS.pdf"},{"file_uploaded":1647,"document_name":"Resultado Final Analista Financeiro Goi\u00e2nia","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ANALISTA-FINANCEIRO-I.pdf"},{"file_uploaded":1648,"document_name":"Resultado Final Assistente Administrativo Goi\u00e2nia","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ASSISTENTE-ADMINISTRATIVO-GOI\u00c2NIA.pdf"},{"file_uploaded":1649,"document_name":"Resultado Final Assistente Administrativo Palmas","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/ASSISTENTE-ADMINISTRATIVO-PALMAS.pdf"},{"file_uploaded":1650,"document_name":"Portaria de Nome\u00e7\u00e3o","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/Portaria-11-2013-AMANDA-BRUNA-KARLA-IZIS-JANAINA-THIAGO-CRP-09.pdf"},{"file_uploaded":1651,"document_name":"Publica\u00e7\u00e3o da Prorroga\u00e7\u00e3o do Concurso","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/PUBLICA\u00c7\u00c3O-PRORROGA\u00c7\u00c3O-CONCURSO-01-2012.pdf"},{"file_uploaded":1652,"document_name":"Portaria de Nome\u00e7\u00e3o","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/Portaria-CRP-09-015-2014.pdf"},{"file_uploaded":1653,"document_name":"Portaria de Nome\u00e7\u00e3o","link":"https:\/\/transparencia.cfp.org.br\/crp09\/wp-content\/uploads\/sites\/21\/2017\/02\/Portaria-CRP-09-003-2015.pdf"}]}