{"id":6969,"slug":"relatorio-de-auditoria-exercicio-2018","link":"https:\/\/transparencia.cfp.org.br\/crp07\/planejamento\/relatorio-de-auditoria-exercicio-2018\/","class_list":["post-6969","planejamento","type-planejamento","status-publish","hentry","planejamento_relatorio-controle-interno-externo"],"documentos":[{"file_uploaded":6971,"document_name":"Relat\u00f3rio de Auditoria Exerc\u00edcio 2018","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2020\/07\/CRP-7-RS-Relat\u00f3rioFormaLonga_2018.pdf"}],"_planejamento_relatorio":[{"id":36,"nome":"Controle Interno\/Externo","slug":"controle-interno-externo","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/planejamento?planejamentorelatorio=controle-interno-externo"}],"titulo":"Relat\u00f3rio de Auditoria Exerc\u00edcio 2018","conteudo":""}