{"id":137,"slug":"relatorio-de-auditoria-do-exercicio-2013","link":"https:\/\/transparencia.cfp.org.br\/crp07\/planejamento\/relatorio-de-auditoria-do-exercicio-2013\/","class_list":["post-137","planejamento","type-planejamento","status-publish","hentry","planejamento_relatorio-controle-interno-externo"],"documentos":[{"file_uploaded":2384,"document_name":"Relat\u00f3rio Auditores Independentes - 2013","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2013\/12\/Relat\u00f3rio-Auditores-Independentes-2013.pdf"}],"_planejamento_relatorio":[{"id":36,"nome":"Controle Interno\/Externo","slug":"controle-interno-externo","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/planejamento?planejamentorelatorio=controle-interno-externo"}],"titulo":"Relat\u00f3rio de Auditoria do Exerc\u00edcio 2013","conteudo":"Relat\u00f3rio dos auditores independentes sobre as demonstra\u00e7\u00f5es cont\u00e1beis.\n"}