{"id":9982,"slug":"portaria-no-101-2022-indicar-representantes-para-o-conselho-estadual-de-direitos-humanos","link":"https:\/\/transparencia.cfp.org.br\/crp07\/legislacao\/portaria-no-101-2022-indicar-representantes-para-o-conselho-estadual-de-direitos-humanos\/","class_list":["post-9982","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-portarias-do-crp"],"titulo":"Portaria n\u00ba 101\/2022 Indicar Representantes para o Conselho Estadual de Direitos Humanos","conteudo":"","documentos":[{"file_uploaded":9983,"document_name":"Portaria n\u00ba 101\/2022 Indicar Representantes para o Conselho Estadual de Direitos Humanos","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2023\/02\/101.22.pdf"}],"_legislacao_categoria":[{"id":82,"nome":"Portarias do CRP","slug":"portarias-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=portarias-do-crp"}]}