{"id":3970,"slug":"portaria-no-050-2017-representantes-no-cmas-de-marau-rs","link":"https:\/\/transparencia.cfp.org.br\/crp07\/legislacao\/portaria-no-050-2017-representantes-no-cmas-de-marau-rs\/","class_list":["post-3970","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-portarias-do-crp"],"titulo":"Portaria n\u00ba 050\/2017 \u2013 Representantes no CMAS de Marau \u2013 RS","conteudo":"","documentos":[{"file_uploaded":3971,"document_name":"Portaria n\u00ba 050\/2017 \u2013 Representantes no CMAS de Marau \u2013 RS","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2018\/01\/Portaria-050-2017.pdf"}],"_legislacao_categoria":[{"id":82,"nome":"Portarias do CRP","slug":"portarias-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=portarias-do-crp"}]}