{"id":10209,"slug":"portaria-024-2023-constituir-o-grupo-de-trabalho-gt-do-planejamento-estrategico","link":"https:\/\/transparencia.cfp.org.br\/crp07\/legislacao\/portaria-024-2023-constituir-o-grupo-de-trabalho-gt-do-planejamento-estrategico\/","class_list":["post-10209","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-portarias-do-crp"],"titulo":"Portaria 024\/2023 Constituir o Grupo de Trabalho \u2013 GT do Planejamento Estrat\u00e9gico","conteudo":"","documentos":[{"file_uploaded":10210,"document_name":"Portaria 024\/2023 Constituir o Grupo de Trabalho - GT do Planejamento Estrat\u00e9gico","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2023\/04\/24.23.pdf"}],"_legislacao_categoria":[{"id":82,"nome":"Portarias do CRP","slug":"portarias-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=portarias-do-crp"}]}