{"id":973,"slug":"oficios-de-homologacao-das-chapas-regionais-2016","link":"https:\/\/transparencia.cfp.org.br\/crp07\/eleicao\/oficios-de-homologacao-das-chapas-regionais-2016\/","class_list":["post-973","eleicao","type-eleicao","status-publish","hentry"],"documentos":[{"file_uploaded":1755,"document_name":"of\u00edcios de homologa\u00e7\u00e3o das chapas concorrentes para o Conselho Regional de Psicologia","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2016\/11\/Homologa\u00e7\u00e3o-Chapas-inscritas.pdf"}],"titulo":"Of\u00edcios de homologa\u00e7\u00e3o das chapas concorrentes 2016","conteudo":"Documento reunindo os of\u00edcios de homologa\u00e7\u00e3o das chapas concorrentes para o Conselho Regional\u00a0de Psicologia em 2016.\n"}