{"id":965,"slug":"resultado-final-eleicoes-e-consulta-nacional-2016","link":"https:\/\/transparencia.cfp.org.br\/crp07\/eleicao\/resultado-final-eleicoes-e-consulta-nacional-2016\/","class_list":["post-965","eleicao","type-eleicao","status-publish","hentry"],"documentos":[{"file_uploaded":1759,"document_name":"Relat\u00f3rio do resultado final Elei\u00e7\u00f5es e da Consulta Nacional 2016","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2016\/09\/Relat\u00f3rio-do-resultado-final-Elei\u00e7\u00f5es-e-da-Consulta-Nacional-2016s.pdf"},{"file_uploaded":1787,"document_name":"Estat\u00edsticas da Consulta Nacional 2016","link":"https:\/\/transparencia.cfp.org.br\/crp07\/wp-content\/uploads\/sites\/8\/2016\/09\/Processo-Eleitoral-Apaf-APRESENTA\u00c7\u00c3O.pdf"}],"titulo":"Resultado final Elei\u00e7\u00f5es e Consulta Nacional 2016","conteudo":"Relat\u00f3rio\u00a0do resultado final Elei\u00e7\u00f5es e da Consulta Nacional 2016\n"}