
{"id":10498,"slug":"portaria-crp-n-19-2025","link":"https:\/\/transparencia.cfp.org.br\/crp06\/legislacao\/portaria-crp-n-19-2025\/","class_list":["post-10498","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-portarias-do-crp"],"titulo":"Portaria CRP n. 19\/2025","conteudo":"Nomeia a Comiss\u00e3o de Sindic\u00e2ncia com a finalidade de apurar a n\u00e3o localiza\u00e7\u00e3o de itens do ativo imobilizado pertencente ao patrim\u00f4nio, deste Conselho Regional de Psicologia da 6\u00aa Regi\u00e3o \u2013 CRP-06\n\n\n","documentos":[{"file_uploaded":10499,"document_name":"Portaria CRP n. 19\/2025","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2025\/01\/Portaria-19-2025.pdf"}],"_legislacao_categoria":[{"id":45,"nome":"Portarias do CRP","slug":"portarias-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=portarias-do-crp"}]}