{"id":10028,"slug":"edital-de-transferencia-interna-especialista-tecnica-psicologa-na-subsede-do-alto-tiete","link":"https:\/\/transparencia.cfp.org.br\/crp06\/legislacao\/edital-de-transferencia-interna-especialista-tecnica-psicologa-na-subsede-do-alto-tiete\/","class_list":["post-10028","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-editais-de-transferencia"],"titulo":"Edital de transfer\u00eancia interna \u2013 Especialista T\u00e9cnica \/ Psic\u00f3loga na Subsede do Alto Tiet\u00ea","conteudo":"\u00a0\n\n","documentos":[{"file_uploaded":10029,"document_name":" Edital de transfer\u00eancia interna - Especialista T\u00e9cnica \/ Psic\u00f3loga na Subsede do Alto Tiet\u00ea","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2024\/08\/Edital-Alto-Tiete.pdf"}],"_legislacao_categoria":[{"id":75,"nome":"Editais de transfer\u00eancia","slug":"editais-de-transferencia","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=editais-de-transferencia"}]}