{"id":5404,"slug":"notas-explicativas-as-demonstracoes-contabeis-2017","link":"https:\/\/transparencia.cfp.org.br\/crp06\/financa\/notas-explicativas-as-demonstracoes-contabeis-2017\/","class_list":["post-5404","financa","type-financa","status-publish","hentry","financa_demonstrativo-notas-explicativas"],"documentos":[{"file_uploaded":5405,"document_name":"Notas Explicativas Exerc\u00edcio 2017.","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2021\/03\/Nota-Explicativa-2017-1.pdf"}],"_financa_demonstrativo":[{"id":59,"nome":"Notas explicativas","slug":"notas-explicativas","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=notas-explicativas"}],"titulo":"Notas Explicativas \u00e0s Demonstra\u00e7\u00f5es Cont\u00e1beis 2017","conteudo":"Notas Explicativas Exerc\u00edcio 2017.\n\u00a0\n"}