{"id":8521,"slug":"concurso-publico-crp-no-01-2023","link":"https:\/\/transparencia.cfp.org.br\/crp06\/concurso\/concurso-publico-crp-no-01-2023\/","class_list":["post-8521","concurso","type-concurso","status-publish","hentry"],"titulo":"Concurso P\u00fablico CRP N\u00ba 01\/2023","conteudo":"O CONSELHO REGIONAL DE PSICOLOGIA DA 6\u00aa REGI\u00c3O \u2013 CRP06 no uso de suas atribui\u00e7\u00f5es legais, mediante as condi\u00e7\u00f5es estipuladas neste Edital, nos termos da legisla\u00e7\u00e3o federal pertinente e Portaria CRP-06 N\u00ba 50\/2023, de 24 de agosto de 2023, torna p\u00fablica a abertura de inscri\u00e7\u00f5es para o Concurso P\u00fablico, para provimento dos empregos\n\n\n\n\n\n","documentos":[{"file_uploaded":8530,"document_name":"Edital de abertura - Concurso P\u00fablico CRP N\u00ba 01\/2023","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2024\/08\/EDITAL_FINAL_CRP_29082023-8-ALTERA-CRONOGRAMA-ASSINADO.pdf"},{"file_uploaded":8535,"document_name":"RETIFICA\u00c7\u00c3O - Edital de abertura - Concurso P\u00fablico CRP N\u00ba 01\/2023","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/2EDITAL_FINAL_CRP_01092023-3-ultima-versao-RE-RATIFICACAO.pdf"},{"file_uploaded":8736,"document_name":"Lista dos\/das candidatos\/as inscritos\/as como ampla concorr\u00eancia, lista dos\/das candidatos\/as inscritos\/as como pessoa com defici\u00eancia, lista dos\/as candidatos\/as inscritos\/as como negros\/as","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/lista-de-inscritos.pdf"},{"file_uploaded":8737,"document_name":"Convoca\u00e7\u00e3o para realiza\u00e7\u00e3o das provas objetivas, provas discursivas e entrega de documenta\u00e7\u00e3o referente \u00e0 avalia\u00e7\u00e3o de t\u00edtulos","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/convocacao-para-realizacao-das-provas.pdf"},{"file_uploaded":8816,"document_name":"Gabaritos das provas objetivas realizadas em 29 de outubro de 2023","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/gabaritos_CRP_30102023.pdf"},{"file_uploaded":9016,"document_name":" Classifica\u00e7\u00e3o final e homologa\u00e7\u00e3o","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/CLASSIFICAO_FINAL_HOMOLOGACAO_crp_08122023.pdf"},{"file_uploaded":9095,"document_name":"Convoca\u00e7\u00e3o de Candidatos (19\/01\/2024)","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-DOU-1-CONV-Concurso-Publico-001-2023.pdf"},{"file_uploaded":9103,"document_name":"Convoca\u00e7\u00e3o de Candidata \u2013 Renata Myazi Martins","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-DOU-Publicacao-Convocacao-Renata-MYAZI.pdf"},{"file_uploaded":9121,"document_name":"Convoca\u00e7\u00e3o de Candidata \u2013 Iara Freitas","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-convocacao-Iara-Freitas.pdf"},{"file_uploaded":9122,"document_name":"Convoca\u00e7\u00e3o de Candidato \u2013 Matheus Lucas Ribeiro Guimaraes","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Convocacao-de-candidado_Matheus-Lucas-Ribeiro-Guimarae-pag210.pdf"},{"file_uploaded":9187,"document_name":"Convoca\u00e7\u00e3o - Iris Renata Mourao De Marco","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Convocacao_Iris-Renata-Mourao-De-Marco.pdf"},{"file_uploaded":9260,"document_name":"Convoca\u00e7\u00e3o de Candidatos - 08\/03\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-Edital-Convocacao.pdf"},{"file_uploaded":9379,"document_name":"Convoca\u00e7\u00e3o de candidatos - 26\/03\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/EXTRATO-DOU_Edital-de-Convocacao-de-26.03.2024.pdf"},{"file_uploaded":9602,"document_name":"Convoca\u00e7\u00e3o de candidatos - 23\/05\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-DOU-Convocacao-de-23.05.2026.pdf"},{"file_uploaded":9636,"document_name":"Extrato DOU - Retifica\u00e7\u00e3o de convoca\u00e7\u00e3o - Karen Karoline Andrade de Carvalho - 10\/06\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Retificacao-Convocacao-Karen.pdf"},{"file_uploaded":9880,"document_name":"Convoca\u00e7\u00e3o - Alexandro Quadra Constancio Da Silva - 10\/07\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Conv-Contador-Alexandro.pdf"},{"file_uploaded":9960,"document_name":"Convoca\u00e7\u00e3o - Neonaldo Leres dos Santos - 22\/07\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-Convocacao-001.2023.pdf"},{"file_uploaded":10051,"document_name":"Convoca\u00e7\u00e3o de candidatos - 13\/08\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Extrato-Convocacao-de-13.08.2024.pdf"},{"file_uploaded":10244,"document_name":"Convoca\u00e7\u00e3o de candidatos - 17\/10\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2023\/08\/Portaria-149-2024-Convocacao.pdf"}]}