{"id":6186,"slug":"concurso-publico-para-provimento-de-vagas-e-formacao-de-cadastro-reserva-para-cargos-de-nivel-medio-edital-no-1-de-18-de-abril-de-2022","link":"https:\/\/transparencia.cfp.org.br\/crp06\/concurso\/concurso-publico-para-provimento-de-vagas-e-formacao-de-cadastro-reserva-para-cargos-de-nivel-medio-edital-no-1-de-18-de-abril-de-2022\/","class_list":["post-6186","concurso","type-concurso","status-publish","hentry"],"titulo":"Concurso P\u00fablico CRP N\u00ba 01\/2022","conteudo":"Para provimento de vagas e forma\u00e7\u00e3o de cadastro reserva para cargos de n\u00edvel m\u00e9dio\nDOU: https:\/\/www.in.gov.br\/web\/dou\/-\/edital-n-1-de-13-de-abril-de-2022-393395874\nLINK BANCA REALIZADORA \u2013 QUADRIX: http:\/\/www.quadrix.org.br\/todos-os-concursos\/proximos-concursos\/crpsp-2022\/publicacoes\/edital-no-1-abertura.aspx\n\n\n\n\n\n","documentos":[{"file_uploaded":6192,"document_name":"Edital","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/1_CRP-SP_concurso_publico-_2022_edital-1.pdf"},{"file_uploaded":9261,"document_name":"Convoca\u00e7\u00e3o de Candidatos - 08\/03\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-Edital-Convocacao.pdf"},{"file_uploaded":9378,"document_name":"Convoca\u00e7\u00e3o de candidatos - 26\/03\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/EXTRATO-DOU_Edital-de-Convocacao-de-26.03.2024.pdf"},{"file_uploaded":9476,"document_name":"Convoca\u00e7\u00e3o de candidatos - 08\/04\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU-Convocacao-dia-08-04-2024.pdf"},{"file_uploaded":9471,"document_name":"Convoca\u00e7\u00e3o de candidato - 10\/04\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU-convocacao-de-10-04-2024.pdf"},{"file_uploaded":9534,"document_name":"Convoca\u00e7\u00e3o de candidatos - 29\/04\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato_DOU_Edital_Convocacao_SEDE_de_29.04.2024.pdf"},{"file_uploaded":9567,"document_name":"Convoca\u00e7\u00e3o de Candidatos - 09\/05\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU-Edital-de-convocacao-de-09.05.2024.pdf"},{"file_uploaded":9598,"document_name":"Convoca\u00e7\u00e3o de Candidatos - 10\/05\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU-Convocacao-campinas.pdf"},{"file_uploaded":9604,"document_name":"Convoca\u00e7\u00e3o de candidatos - 23\/05\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU-Convocacao-de-23.05.2026.pdf"},{"file_uploaded":9761,"document_name":"Convoca\u00e7\u00e3o de candidatos - 14\/06\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-DOU_Publi-Edital-Convocacao-de-14-06-2024.pdf"},{"file_uploaded":9860,"document_name":"Convoca\u00e7\u00e3o de candidatos - 28\/06\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-Convocacao-28-06-2024.pdf"},{"file_uploaded":9963,"document_name":"Convoca\u00e7\u00e3o de Candidatos - 17\/06\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-Convocacao-001.2022.pdf"},{"file_uploaded":10053,"document_name":"Convoca\u00e7\u00e3o de candidatos - 13\/08\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Extrato-Convocacao-de-13.08.2024.pdf"},{"file_uploaded":10099,"document_name":"Convoca\u00e7\u00e3o de candidatos - 03\/09\/2024","link":"https:\/\/transparencia.cfp.org.br\/crp06\/wp-content\/uploads\/sites\/29\/2022\/05\/Convocacao-03-09-2024.pdf"}]}