{"id":7065,"slug":"relatorio-de-gestao-xii-plenario-2007-2010","link":"https:\/\/transparencia.cfp.org.br\/crp04\/planejamento\/relatorio-de-gestao-xii-plenario-2007-2010\/","class_list":["post-7065","planejamento","type-planejamento","status-publish","hentry","planejamento_relatorio-relatorios-de-gestao"],"documentos":[{"file_uploaded":7067,"document_name":"Relat\u00f3rio de Gest\u00e3o - XII Plen\u00e1rio - 2007 - 2010","link":"https:\/\/transparencia.cfp.org.br\/crp04\/wp-content\/uploads\/sites\/17\/2024\/07\/Relatorio-de-gestao-2007-2010.pdf"}],"_planejamento_relatorio":[{"id":37,"nome":"Relat\u00f3rios de Gest\u00e3o","slug":"relatorios-de-gestao","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/planejamento?planejamentorelatorio=relatorios-de-gestao"}],"titulo":"Relat\u00f3rio de Gest\u00e3o \u2013 XII Plen\u00e1rio \u2013 2007 \u2013 2010","conteudo":""}