{"slug":"informacoes-sigilosas","excerpt":{"rendered":"<p>Espa\u00e7o reservado para a divulga\u00e7\u00e3o das informa\u00e7\u00f5es classificadas ou desclassificadas nos graus de sigilo definidos no art. 24 da Lei n\u00ba. 12.527\/2011. At\u00e9 o presente momento, o\u00a0Conselho Regional de Psicologia de Minas Gerais (CRP-04)\u00a0n\u00e3o tem\u00a0informa\u00e7\u00f5es classificadas ou desclassificadas nos graus&#8230; <a class=\"moretag\" href=\"https:\/\/transparencia.cfp.org.br\/crp04\/informacao-ao-cidadao\/informacoes-sigilosas\/\">Continue lendo<\/a><\/p>\n","protected":false},"titulo":"Informa\u00e7\u00f5es Sigilosas","conteudo":"Espa\u00e7o reservado para a divulga\u00e7\u00e3o das informa\u00e7\u00f5es classificadas ou desclassificadas nos graus de sigilo definidos no art. 24 da Lei n\u00ba. 12.527\/2011.\nAt\u00e9 o presente momento, o\u00a0Conselho Regional de Psicologia de Minas Gerais (CRP-04)\u00a0n\u00e3o tem\u00a0informa\u00e7\u00f5es classificadas ou desclassificadas nos graus de sigilo \u201csecreta\u201d, \u201cultrassecreta\u201d e \u201creservada\u201d, definidos no art. 24 da Lei n\u00ba 12.527\/2011 (Lei de Acesso \u00e0 Informa\u00e7\u00e3o).\n"}