{"id":8620,"slug":"lei-no-24-134-de-07-de-junho-de-2022","link":"https:\/\/transparencia.cfp.org.br\/crp04\/legislacao\/lei-no-24-134-de-07-de-junho-de-2022\/","class_list":["post-8620","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-leis-e-normas"],"titulo":"Lei n\u00ba 24.134 de 07 de junho de 2022 \u2013 Minas Gerais","conteudo":"Disp\u00f5e sobre as a\u00e7\u00f5es do Estado na preven\u00e7\u00e3o do suic\u00eddio e na promo\u00e7\u00e3o da sa\u00fade mental.\nAcesse a lei na \u00edntegra em : Lei n\u00ba 24.134, de 07 de junho de 2022- Minas Gerais\n","_legislacao_categoria":[{"id":22,"nome":"Leis e normas","slug":"leis-e-normas","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=leis-e-normas"}]}