{"id":8607,"slug":"lei-no-9-029-de-13-de-abril-de-1995","link":"https:\/\/transparencia.cfp.org.br\/crp04\/legislacao\/lei-no-9-029-de-13-de-abril-de-1995\/","class_list":["post-8607","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-leis-e-normas"],"titulo":"Lei n\u00ba 9.029, de 13 de abril de 1995","conteudo":"Pro\u00edbe a exig\u00eancia de atestados de gravidez e esteriliza\u00e7\u00e3o, e outras pr\u00e1ticas discriminat\u00f3rias, para efeitos admissionais ou de perman\u00eancia da rela\u00e7\u00e3o jur\u00eddica de trabalho, e d\u00e1 outras provid\u00eancias.\nAcesse a lei na \u00edntegra em : Lei n\u00ba 9.029, de 13 de abril de 1995\u00a0\n","_legislacao_categoria":[{"id":22,"nome":"Leis e normas","slug":"leis-e-normas","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=leis-e-normas"}]}