{"id":8568,"slug":"lei-no-4-119-de-27-08-1962","link":"https:\/\/transparencia.cfp.org.br\/crp04\/legislacao\/lei-no-4-119-de-27-08-1962\/","class_list":["post-8568","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-leis-e-normas"],"titulo":"Lei n\u00ba 4.119 de 27 de agosto de 1962","conteudo":"Disp\u00f5e sobre os cursos de forma\u00e7\u00e3o em Psicologia e regulamenta a profiss\u00e3o de Psic\u00f3logo.\nAcesse a lei na \u00edntegra em : Lei N\u00ba 4.119 de 27\/08\/1962\n","_legislacao_categoria":[{"id":22,"nome":"Leis e normas","slug":"leis-e-normas","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=leis-e-normas"}]}