{"id":1699,"slug":"resolucao-crp-04-no-0042001","link":"https:\/\/transparencia.cfp.org.br\/crp04\/legislacao\/resolucao-crp-04-no-0042001\/","class_list":["post-1699","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-resolucoes-do-crp"],"titulo":"RESOLU\u00c7\u00c3O CRP-04 n\u00ba 004\/2001","conteudo":"Estabelece crit\u00e9rios de cobran\u00e7a e de negocia\u00e7\u00e3o de anuidades para Pessoas F\u00edsicas.\n RESOLU\u00c7\u00c3O CRP-04 n\u00ba 004\/2001\n","_legislacao_categoria":[{"id":42,"nome":"Resolu\u00e7\u00f5es do CRP 04","slug":"resolucoes-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=resolucoes-do-crp"}]}