{"id":1697,"slug":"resolucao-crp-04-no-0022001","link":"https:\/\/transparencia.cfp.org.br\/crp04\/legislacao\/resolucao-crp-04-no-0022001\/","class_list":["post-1697","legislacao","type-legislacao","status-publish","hentry","legislacao_categoria-resolucoes-do-crp"],"titulo":"RESOLU\u00c7\u00c3O CRP-04 n\u00ba 002\/2001","conteudo":"Estabelece crit\u00e9rios para ressarcimento de despesas com transporte aos Conselheiros, Funcion\u00e1rios, Gestores da Se\u00e7\u00e3o-01 (Esp\u00edrito Santo) e Representantes Oficiais, alterando a Resolu\u00e7\u00e3o CRP\/04-006\/96\n RESOLU\u00c7\u00c3O CRP-04 n\u00ba 002\/2001\n","_legislacao_categoria":[{"id":42,"nome":"Resolu\u00e7\u00f5es do CRP 04","slug":"resolucoes-do-crp","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/legislacao?legislacaocategoria=resolucoes-do-crp"}]}