{"id":7594,"slug":"balanco-orcamentario-crp04-mg-exercicio-2024","link":"https:\/\/transparencia.cfp.org.br\/crp04\/financa\/balanco-orcamentario-crp04-mg-exercicio-2024\/","class_list":["post-7594","financa","type-financa","status-publish","hentry","financa_demonstrativo-balanco-orcamentario"],"documentos":[{"file_uploaded":7595,"document_name":"BALAN\u00c7O OR\u00c7AMENT\u00c1RIO CRP04-MG EXERC\u00cdCIO 2024","link":"https:\/\/transparencia.cfp.org.br\/crp04\/wp-content\/uploads\/sites\/17\/2025\/03\/Balanco-Orcamentario-2024.pdf"}],"_financa_demonstrativo":[{"id":6,"nome":"Balan\u00e7o Or\u00e7ament\u00e1rio","slug":"balanco-orcamentario","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=balanco-orcamentario"}],"titulo":"BALAN\u00c7O OR\u00c7AMENT\u00c1RIO CRP04-MG EXERC\u00cdCIO 2024","conteudo":""}