{"id":5306,"slug":"processo-seletivo-simplificado-crp-04-mg-no-001-21","link":"https:\/\/transparencia.cfp.org.br\/crp04\/concurso\/processo-seletivo-simplificado-crp-04-mg-no-001-21\/","class_list":["post-5306","concurso","type-concurso","status-publish","hentry"],"titulo":"Processo Seletivo Simplificado CRP 04 MG \u2013 Edital n\u00ba 001\/21","conteudo":"O Conselho Regional de Psicologia \u2013 Minas Gerais (CRP-MG) torna p\u00fablica a realiza\u00e7\u00e3o de Processo Seletivo Simplificado (PSS) para fins de contrata\u00e7\u00e3o tempor\u00e1ria para provimento de jornalista, especificamente, para substitui\u00e7\u00e3o de empregada(o) p\u00fablica efetiva do CRP-MG, que esteja em gozo de f\u00e9rias, licen\u00e7as e outras previs\u00f5es de afastamentos tempor\u00e1rios, visando atender \u00e0 necessidade transit\u00f3ria ou de acr\u00e9scimo extraordin\u00e1rio de servi\u00e7os.\n\u00a0\nEdital Processo Seletivo Simplificado CRP 04 MG de 01-21\n","documentos":[{"file_uploaded":5358,"document_name":"Publica\u00e7\u00e3o Resultado PSS Jornalista","link":"https:\/\/transparencia.cfp.org.br\/crp04\/wp-content\/uploads\/sites\/17\/2021\/08\/Publicacao_DOU_08__09_resultado_PSS_jornalista-1.pdf"},{"file_uploaded":5359,"document_name":"Publica\u00e7\u00e3o Homologa\u00e7\u00e3o PSS Jornalista","link":"https:\/\/transparencia.cfp.org.br\/crp04\/wp-content\/uploads\/sites\/17\/2021\/08\/Publicacao_DOU_13_09_homologacao_PSS_jornalista_e_Volta_de_Fase_Pregao_05_2021.pdf"},{"file_uploaded":5360,"document_name":"Classifica\u00e7\u00e3o Final","link":"https:\/\/transparencia.cfp.org.br\/crp04\/wp-content\/uploads\/sites\/17\/2021\/08\/resultado_classificacacao_final_prazorecurso_jornalista.pdf"}]}