
{"id":2808,"slug":"notas-explicativas-2014","link":"https:\/\/transparencia.cfp.org.br\/crp03\/financa\/notas-explicativas-2014\/","class_list":["post-2808","financa","type-financa","status-publish","hentry","financa_demonstrativo-notas-explicativas"],"documentos":[{"file_uploaded":2809,"document_name":"Notas Explicativas 2014","link":"https:\/\/transparencia.cfp.org.br\/crp03\/wp-content\/uploads\/sites\/13\/2021\/03\/Notas-Explicativas-2014.pdf"}],"_financa_demonstrativo":[{"id":51,"nome":"Notas explicativas","slug":"notas-explicativas","link":"https:\/\/dev-transparencia.cfp.org.br\/wp-json\/wp\/v2\/financa?financademonstrativo=notas-explicativas"}],"titulo":"Notas Explicativas 2014","conteudo":"Notas Explicativas 2014.\n"}